{"id":52,"date":"2024-06-11T18:23:49","date_gmt":"2024-06-11T18:23:49","guid":{"rendered":"https:\/\/www.frydenspark.dk\/?page_id=52"},"modified":"2026-01-15T14:46:32","modified_gmt":"2026-01-15T14:46:32","slug":"galleri","status":"publish","type":"page","link":"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/galleri\/","title":{"rendered":"Galleri"},"content":{"rendered":"<style>.kb-row-layout-id52_bf06f0-33 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id52_bf06f0-33 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id52_bf06f0-33 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-5xl, 10rem);padding-bottom:var(--global-kb-spacing-5xl, 10rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id52_bf06f0-33{background-image:url('https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00239-scaled.jpg');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id52_bf06f0-33 > .kt-row-layout-overlay{opacity:0.90;background:linear-gradient(135deg,var(--global-palette1,#ffffff) 0%,var(--global-palette2,#EDF2F7) 100%);mix-blend-mode:normal;}.kb-row-layout-id52_bf06f0-33 .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id52_bf06f0-33 .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id52_bf06f0-33 .kt-row-layout-bottom-sep svg{fill:var(--global-palette9, #ffffff)!important;}@media all and (max-width: 1024px){.kb-row-layout-id52_bf06f0-33 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id52_bf06f0-33 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id52_bf06f0-33 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id52_bf06f0-33 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-3xl, 6.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id52_bf06f0-33 .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id52_bf06f0-33 .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id52_bf06f0-33 alignfull kt-row-has-bg kb-divider-static wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-layout-bottom-sep kt-row-sep-type-sltl\"><svg viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\"><path d=\"M1000,0l-1000,100l1000,0l0,-100Z\" \/><\/svg><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column52_6d62b2-fa > .kt-inside-inner-col,.kadence-column52_6d62b2-fa > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column52_6d62b2-fa > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column52_6d62b2-fa > .kt-inside-inner-col{flex-direction:column;}.kadence-column52_6d62b2-fa > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column52_6d62b2-fa > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column52_6d62b2-fa{position:relative;}@media all and (max-width: 1024px){.kadence-column52_6d62b2-fa > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column52_6d62b2-fa > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column52_6d62b2-fa inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading52_f03749-62, .wp-block-kadence-advancedheading.kt-adv-heading52_f03749-62[data-kb-block=\"kb-adv-heading52_f03749-62\"]{margin-top:var(--global-kb-spacing-xs, 1rem);text-align:center;font-size:var(--global-kb-font-size-xl, 3rem);line-height:1;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading52_f03749-62 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading52_f03749-62[data-kb-block=\"kb-adv-heading52_f03749-62\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading52_f03749-62 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading52_f03749-62[data-kb-block=\"kb-adv-heading52_f03749-62\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading52_f03749-62, .wp-block-kadence-advancedheading.kt-adv-heading52_f03749-62[data-kb-block=\"kb-adv-heading52_f03749-62\"]{font-size:60px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading52_f03749-62, .wp-block-kadence-advancedheading.kt-adv-heading52_f03749-62[data-kb-block=\"kb-adv-heading52_f03749-62\"]{font-size:40px;}}<\/style>\n<h1 class=\"kt-adv-heading52_f03749-62 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading52_f03749-62\">Din Afdelings galleri<\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading52_169220-a6, .wp-block-kadence-advancedheading.kt-adv-heading52_169220-a6[data-kb-block=\"kb-adv-heading52_169220-a6\"]{display:block;text-align:center;font-size:20px;line-height:1;font-weight:300;font-style:normal;letter-spacing:1px;}.wp-block-kadence-advancedheading.kt-adv-heading52_169220-a6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading52_169220-a6[data-kb-block=\"kb-adv-heading52_169220-a6\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading52_169220-a6 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading52_169220-a6[data-kb-block=\"kb-adv-heading52_169220-a6\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<span class=\"kt-adv-heading52_169220-a6 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading52_169220-a6\">Tilk\u00f8b en fotopakke til Din Afdeling<\/span>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kadence-column52_1dc9a7-50 > .kt-inside-inner-col{display:flex;}.kadence-column52_1dc9a7-50 > .kt-inside-inner-col,.kadence-column52_1dc9a7-50 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column52_1dc9a7-50 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column52_1dc9a7-50 > .kt-inside-inner-col{flex-direction:column;align-items:center;}.kadence-column52_1dc9a7-50 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column52_1dc9a7-50 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column52_1dc9a7-50 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column52_1dc9a7-50 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column52_1dc9a7-50{position:relative;}@media all and (max-width: 1024px){.kadence-column52_1dc9a7-50 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kadence-column52_1dc9a7-50 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column52_1dc9a7-50 kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><nav aria-label=\"breadcrumbs\" role=\"navigation\" class=\"surerank-breadcrumbs\"><p><span class=\"last\">Forside<\/span><\/p><\/nav>\n<\/div><\/div>\n\n\n<style>.kb-row-layout-id52_7aa253-bd > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id52_7aa253-bd > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id52_7aa253-bd > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id52_7aa253-bd > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id52_7aa253-bd > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id52_7aa253-bd > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id52_7aa253-bd alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column52_601b7f-f4 > .kt-inside-inner-col{padding-top:0px;padding-bottom:0px;}.kadence-column52_601b7f-f4 > .kt-inside-inner-col,.kadence-column52_601b7f-f4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column52_601b7f-f4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column52_601b7f-f4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column52_601b7f-f4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column52_601b7f-f4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column52_601b7f-f4{position:relative;}@media all and (max-width: 1024px){.kadence-column52_601b7f-f4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column52_601b7f-f4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column52_601b7f-f4\"><div class=\"kt-inside-inner-col\"><style>.kadence-column52_70619a-bc{max-width:750px;margin-left:auto;margin-right:auto;}.wp-block-kadence-column.kb-section-dir-horizontal:not(.kb-section-md-dir-vertical)>.kt-inside-inner-col>.kadence-column52_70619a-bc{-webkit-flex:0 1 750px;flex:0 1 750px;max-width:unset;margin-left:unset;margin-right:unset;}.kadence-column52_70619a-bc > .kt-inside-inner-col,.kadence-column52_70619a-bc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column52_70619a-bc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column52_70619a-bc > .kt-inside-inner-col{flex-direction:column;}.kadence-column52_70619a-bc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column52_70619a-bc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column52_70619a-bc{text-align:center;}.kadence-column52_70619a-bc{position:relative;}@media all and (min-width: 1025px){.wp-block-kadence-column.kb-section-dir-horizontal>.kt-inside-inner-col>.kadence-column52_70619a-bc{-webkit-flex:0 1 750px;flex:0 1 750px;max-width:unset;margin-left:unset;margin-right:unset;}}@media all and (max-width: 1024px){.kadence-column52_70619a-bc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.wp-block-kadence-column.kb-section-sm-dir-vertical:not(.kb-section-sm-dir-horizontal):not(.kb-section-sm-dir-specificity)>.kt-inside-inner-col>.kadence-column52_70619a-bc{max-width:750px;-webkit-flex:1;flex:1;margin-left:auto;margin-right:auto;}.kadence-column52_70619a-bc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column52_70619a-bc\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading52_5ca52e-b0, .wp-block-kadence-advancedheading.kt-adv-heading52_5ca52e-b0[data-kb-block=\"kb-adv-heading52_5ca52e-b0\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading52_5ca52e-b0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading52_5ca52e-b0[data-kb-block=\"kb-adv-heading52_5ca52e-b0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading52_5ca52e-b0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading52_5ca52e-b0[data-kb-block=\"kb-adv-heading52_5ca52e-b0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading52_5ca52e-b0 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading52_5ca52e-b0\">Tilk\u00f8b en fotopakke til Din Afdelings nye hjemmeside, og f\u00e5 den pr\u00e6senteret p\u00e5 en flot og inspirerende m\u00e5de som eksemplet herunder.<\/h3>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column52_aca56b-ee > .kt-inside-inner-col,.kadence-column52_aca56b-ee > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column52_aca56b-ee > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column52_aca56b-ee > .kt-inside-inner-col{flex-direction:column;}.kadence-column52_aca56b-ee > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column52_aca56b-ee > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column52_aca56b-ee{position:relative;}@media all and (max-width: 1024px){.kadence-column52_aca56b-ee > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column52_aca56b-ee > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column52_aca56b-ee\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedgallery .kb-gallery-type-masonry.kb-gallery-id-52_eac1df-b4{margin:-16px;}.kb-gallery-type-masonry.kb-gallery-id-52_eac1df-b4 .kadence-blocks-gallery-item{padding:16px;}.kb-gallery-id-52_eac1df-b4 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-52_eac1df-b4 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-52_eac1df-b4 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-masonry kb-masonry-init kb-gallery-id-52_eac1df-b4 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00239-scaled.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00239-scaled-1024x576.jpg\" width=\"1024\" height=\"576\" alt=\"DSC00239 Scaled 1024x576\" data-full-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00239-scaled.jpg\" data-light-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00239-scaled.jpg\" data-id=\"188\" class=\"wp-image-188\" title=\"Galleri\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00258-scaled.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00258-scaled-1024x576.jpg\" width=\"1024\" height=\"576\" alt=\"DSC00258 Scaled 1024x576\" data-full-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00258-scaled.jpg\" data-light-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00258-scaled.jpg\" data-id=\"197\" class=\"wp-image-197\" title=\"Galleri\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00263-scaled.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00263-scaled-1024x576.jpg\" width=\"1024\" height=\"576\" alt=\"DSC00263 Scaled 1024x576\" data-full-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00263-scaled.jpg\" data-light-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00263-scaled.jpg\" data-id=\"201\" class=\"wp-image-201\" title=\"Galleri\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00273-scaled.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00273-scaled-1024x576.jpg\" width=\"1024\" height=\"576\" alt=\"DSC00273 Scaled 1024x576\" data-full-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00273-scaled.jpg\" data-light-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00273-scaled.jpg\" data-id=\"206\" class=\"wp-image-206\" title=\"Galleri\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00308-scaled.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00308-scaled-1024x576.jpg\" width=\"1024\" height=\"576\" alt=\"DSC00308 Scaled 1024x576\" data-full-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00308-scaled.jpg\" data-light-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00308-scaled.jpg\" data-id=\"231\" class=\"wp-image-231\" title=\"Galleri\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00302-scaled.jpg\" data-alt=\"Velkommen til Frydenspark | En boligafdeling centralt beliggende p\u00e5 Amager, med 294 l\u00e6kre lejligheder med store altaner og masser af gr\u00f8nne omr\u00e5der\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00302-scaled-1024x576.jpg\" width=\"1024\" height=\"576\" alt=\"Velkommen til Frydenspark | En boligafdeling centralt beliggende p\u00e5 Amager, med 294 l\u00e6kre lejligheder med store altaner og masser af gr\u00f8nne omr\u00e5der\" data-full-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00302-scaled.jpg\" data-light-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00302-scaled.jpg\" data-id=\"228\" class=\"wp-image-228\" title=\"Galleri\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00298-scaled.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00298-scaled-1024x576.jpg\" width=\"1024\" height=\"576\" alt=\"DSC00298 Scaled 1024x576\" data-full-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00298-scaled.jpg\" data-light-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00298-scaled.jpg\" data-id=\"226\" class=\"wp-image-226\" title=\"Galleri\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00290-scaled.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00290-scaled-1024x576.jpg\" width=\"1024\" height=\"576\" alt=\"DSC00290 Scaled 1024x576\" data-full-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00290-scaled.jpg\" data-light-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00290-scaled.jpg\" data-id=\"218\" class=\"wp-image-218\" title=\"Galleri\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00321-scaled.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00321-scaled-1024x576.jpg\" width=\"1024\" height=\"576\" alt=\"DSC00321 Scaled 1024x576\" data-full-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00321-scaled.jpg\" data-light-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00321-scaled.jpg\" data-id=\"240\" class=\"wp-image-240\" title=\"Galleri\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00285-scaled.jpg\" data-alt=\"Frydenspark\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00285-scaled-1024x576.jpg\" width=\"1024\" height=\"576\" alt=\"Frydenspark\" data-full-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00285-scaled.jpg\" data-light-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00285-scaled.jpg\" data-id=\"213\" class=\"wp-image-213\" title=\"Galleri\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00312-scaled.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00312-scaled-1024x576.jpg\" width=\"1024\" height=\"576\" alt=\"DSC00312 Scaled 1024x576\" data-full-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00312-scaled.jpg\" data-light-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00312-scaled.jpg\" data-id=\"233\" class=\"wp-image-233\" title=\"Galleri\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00315-scaled.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00315-scaled-1024x576.jpg\" width=\"1024\" height=\"576\" alt=\"DSC00315 Scaled 1024x576\" data-full-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00315-scaled.jpg\" data-light-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00315-scaled.jpg\" data-id=\"234\" class=\"wp-image-234\" title=\"Galleri\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00287-scaled.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00287-scaled-1024x576.jpg\" width=\"1024\" height=\"576\" alt=\"DSC00287 Scaled 1024x576\" data-full-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00287-scaled.jpg\" data-light-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00287-scaled.jpg\" data-id=\"215\" class=\"wp-image-215\" title=\"Galleri\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00318-scaled.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00318-scaled-1024x576.jpg\" width=\"1024\" height=\"576\" alt=\"DSC00318 Scaled 1024x576\" data-full-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00318-scaled.jpg\" data-light-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00318-scaled.jpg\" data-id=\"237\" class=\"wp-image-237\" title=\"Galleri\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00288-scaled.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00288-scaled-1024x576.jpg\" width=\"1024\" height=\"576\" alt=\"DSC00288 Scaled 1024x576\" data-full-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00288-scaled.jpg\" data-light-image=\"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00288-scaled.jpg\" data-id=\"216\" class=\"wp-image-216\" title=\"Galleri\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><\/ul><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id52_a65126-91 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id52_a65126-91 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id52_a65126-91 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-4xl, 8rem);padding-bottom:var(--global-kb-spacing-4xl, 8rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id52_a65126-91{background-image:linear-gradient(135deg,var(--global-palette1,#ffffff) 41%,var(--global-palette2,#eef2f5) 100%);}.kb-row-layout-id52_a65126-91 > .kt-row-layout-overlay{opacity:0.20;background-image:url('https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00308-scaled.jpg');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;mix-blend-mode:multiply;}@media all and (max-width: 1024px){.kb-row-layout-id52_a65126-91 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id52_a65126-91 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id52_a65126-91 alignfull has-theme-palette2-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column52_dedd6c-38 > .kt-inside-inner-col,.kadence-column52_dedd6c-38 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column52_dedd6c-38 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column52_dedd6c-38 > .kt-inside-inner-col{flex-direction:column;}.kadence-column52_dedd6c-38 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column52_dedd6c-38 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column52_dedd6c-38{position:relative;}@media all and (max-width: 1024px){.kadence-column52_dedd6c-38 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column52_dedd6c-38 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column52_dedd6c-38 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading52_6568e8-43, .wp-block-kadence-advancedheading.kt-adv-heading52_6568e8-43[data-kb-block=\"kb-adv-heading52_6568e8-43\"]{display:block;text-align:center;font-size:var(--global-kb-font-size-sm, 0.9rem);line-height:1;font-style:normal;text-transform:uppercase;letter-spacing:1px;}.wp-block-kadence-advancedheading.kt-adv-heading52_6568e8-43 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading52_6568e8-43[data-kb-block=\"kb-adv-heading52_6568e8-43\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading52_6568e8-43 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading52_6568e8-43[data-kb-block=\"kb-adv-heading52_6568e8-43\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<span class=\"kt-adv-heading52_6568e8-43 wp-block-kadence-advancedheading has-theme-palette-8-color has-text-color\" data-kb-block=\"kb-adv-heading52_6568e8-43\">Vil du flytte til Din afdeling?<\/span>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading52_b997ce-23, .wp-block-kadence-advancedheading.kt-adv-heading52_b997ce-23[data-kb-block=\"kb-adv-heading52_b997ce-23\"]{margin-top:var(--global-kb-spacing-xs, 1rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:center;font-size:var(--global-kb-font-size-xl, 3rem);line-height:1.1;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading52_b997ce-23 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading52_b997ce-23[data-kb-block=\"kb-adv-heading52_b997ce-23\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading52_b997ce-23 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading52_b997ce-23[data-kb-block=\"kb-adv-heading52_b997ce-23\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading52_b997ce-23 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading52_b997ce-23\">Link ind til jeres administration her fra<\/h2>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns52_9b0087-b4{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns52_9b0087-b4 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns52_9b0087-b4\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn52_38e9d6-51.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn52_38e9d6-51.kb-button{color:var(--global-palette9, #ffffff);border-top-color:var(--global-palette9, #ffffff);border-top-style:solid;border-right-color:var(--global-palette9, #ffffff);border-right-style:solid;border-bottom-color:var(--global-palette9, #ffffff);border-bottom-style:solid;border-left-color:var(--global-palette9, #ffffff);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn52_38e9d6-51.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn52_38e9d6-51.kb-button:focus{color:var(--global-palette9, #ffffff);border-top-color:var(--global-palette9, #ffffff);border-top-style:solid;border-right-color:var(--global-palette9, #ffffff);border-right-style:solid;border-bottom-color:var(--global-palette9, #ffffff);border-bottom-style:solid;border-left-color:var(--global-palette9, #ffffff);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn52_38e9d6-51.kb-button{border-top-color:var(--global-palette9, #ffffff);border-top-style:solid;border-right-color:var(--global-palette9, #ffffff);border-right-style:solid;border-bottom-color:var(--global-palette9, #ffffff);border-bottom-style:solid;border-left-color:var(--global-palette9, #ffffff);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn52_38e9d6-51.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn52_38e9d6-51.kb-button:focus{border-top-color:var(--global-palette9, #ffffff);border-top-style:solid;border-right-color:var(--global-palette9, #ffffff);border-right-style:solid;border-bottom-color:var(--global-palette9, #ffffff);border-bottom-style:solid;border-left-color:var(--global-palette9, #ffffff);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn52_38e9d6-51.kb-button{border-top-color:var(--global-palette9, #ffffff);border-top-style:solid;border-right-color:var(--global-palette9, #ffffff);border-right-style:solid;border-bottom-color:var(--global-palette9, #ffffff);border-bottom-style:solid;border-left-color:var(--global-palette9, #ffffff);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn52_38e9d6-51.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn52_38e9d6-51.kb-button:focus{border-top-color:var(--global-palette9, #ffffff);border-top-style:solid;border-right-color:var(--global-palette9, #ffffff);border-right-style:solid;border-bottom-color:var(--global-palette9, #ffffff);border-bottom-style:solid;border-left-color:var(--global-palette9, #ffffff);border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn52_38e9d6-51 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-true kb-btn-global-inherit wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Skriv mig op<\/span><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-btn-icon-side-right\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Din Afdelings galleri Tilk\u00f8b en fotopakke til Din Afdeling Tilk\u00f8b en fotopakke til Din Afdelings nye hjemmeside, og f\u00e5 den pr\u00e6senteret p\u00e5 en flot og inspirerende m\u00e5de som eksemplet herunder. Vil du flytte til Din afdeling? Link ind til jeres administration her fra<\/p>\n","protected":false},"author":1,"featured_media":233,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-52","page","type-page","status-publish","has-post-thumbnail","hentry"],"taxonomy_info":[],"featured_image_src_large":["https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-content\/uploads\/Website-filer\/DSC00312-scaled-1024x576.jpg",1024,576,true],"author_info":{"display_name":"admin","author_link":"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/author\/admin\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-json\/wp\/v2\/pages\/52","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-json\/wp\/v2\/comments?post=52"}],"version-history":[{"count":0,"href":"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-json\/wp\/v2\/pages\/52\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-json\/wp\/v2\/media\/233"}],"wp:attachment":[{"href":"https:\/\/demosider.fgroupmedia.dk\/boligforening-neutral\/wp-json\/wp\/v2\/media?parent=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}